{"id":4159,"date":"2019-09-12T14:29:28","date_gmt":"2019-09-12T14:29:28","guid":{"rendered":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/?page_id=4159"},"modified":"2019-09-26T07:31:00","modified_gmt":"2019-09-26T07:31:00","slug":"exhibitions","status":"publish","type":"page","link":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/en\/exhibitions\/","title":{"rendered":"Exhibitions"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-appearance.php","meta":[],"_links":{"self":[{"href":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/wp-json\/wp\/v2\/pages\/4159"}],"collection":[{"href":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/wp-json\/wp\/v2\/comments?post=4159"}],"version-history":[{"count":0,"href":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/wp-json\/wp\/v2\/pages\/4159\/revisions"}],"wp:attachment":[{"href":"https:\/\/wordpress.sitegist.net\/holodomormuseum\/wp-json\/wp\/v2\/media?parent=4159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}